{"id":157,"date":"2025-03-11T11:54:21","date_gmt":"2025-03-11T11:54:21","guid":{"rendered":"https:\/\/paintforestpaintball.es\/?page_id=157"},"modified":"2025-03-11T12:18:04","modified_gmt":"2025-03-11T12:18:04","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/paintforestpaintball.es\/en\/politica-de-cookies\/","title":{"rendered":"Cookies policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"157\" class=\"elementor elementor-157\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d00a749 e-flex e-con-boxed e-con e-parent\" data-id=\"d00a749\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b21ce28 elementor-widget elementor-widget-heading\" data-id=\"b21ce28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Cookies policy<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-833731c elementor-widget elementor-widget-breadcrumbs\" data-id=\"833731c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/paintforestpaintball.es\/en\/\">Inicio<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b37f770 elementor-widget elementor-widget-text-editor\" data-id=\"b37f770\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El acceso a este Sitio Web puede implicar la utilizaci\u00f3n de cookies. Las cookies son peque\u00f1as cantidades de informaci\u00f3n que se almacenan en el navegador utilizado por cada Usuario \u2014en los distintos dispositivos que pueda utilizar para navegar\u2014 para que el servidor recuerde cierta informaci\u00f3n que posteriormente y \u00fanicamente el servidor que la implement\u00f3 leer\u00e1. Las cookies facilitan la navegaci\u00f3n, la hacen m\u00e1s amigable, y no da\u00f1an el dispositivo de navegaci\u00f3n.<\/p><p>Las cookies son procedimientos autom\u00e1ticos de recogida de informaci\u00f3n relativa a las preferencias determinadas por el Usuario durante su visita al Sitio Web con el fin de reconocerlo como Usuario, y personalizar su experiencia y el uso del Sitio Web, y pueden tambi\u00e9n, por ejemplo, ayudar a identificar y resolver errores.<\/p><p>La informaci\u00f3n recabada a trav\u00e9s de las cookies puede incluir la fecha y hora de visitas al Sitio Web, las p\u00e1ginas visionadas, el tiempo que ha estado en el Sitio Web y los sitios visitados justo antes y despu\u00e9s del mismo. Sin embargo, ninguna cookie permite que esta misma pueda contactarse con el n\u00famero de tel\u00e9fono del Usuario o con cualquier otro medio de contacto personal. Ninguna cookie puede extraer informaci\u00f3n del disco duro del Usuario o robar informaci\u00f3n personal. La \u00fanica manera de que la informaci\u00f3n privada del Usuario forme parte del archivo Cookie es que el usuario d\u00e9 personalmente esa informaci\u00f3n al servidor.<\/p><p>Las cookies que permiten identificar a una persona se consideran datos personales. Por tanto, a las mismas les ser\u00e1 de aplicaci\u00f3n la Pol\u00edtica de Privacidad anteriormente descrita. En este sentido, para la utilizaci\u00f3n de las mismas ser\u00e1 necesario el consentimiento del Usuario. Este consentimiento ser\u00e1 comunicado, en base a una elecci\u00f3n aut\u00e9ntica, ofrecido mediante una decisi\u00f3n afirmativa y positiva, antes del tratamiento inicial, removible y documentado.<\/p><h2>Cookies propias<\/h2><p>Son aquellas cookies que son enviadas al ordenador o dispositivo del Usuario y gestionadas exclusivamente por Paintforest paintball para el mejor funcionamiento del Sitio Web. La informaci\u00f3n que se recaba se emplea para mejorar la calidad del Sitio Web y su Contenido y su experiencia como Usuario. Estas cookies permiten reconocer al Usuario como visitante recurrente del Sitio Web y adaptar el contenido para ofrecerle contenidos que se ajusten a sus preferencias.<\/p><h2>Cookies de terceros<\/h2><p>Son cookies utilizadas y gestionadas por entidades externas que proporcionan a Paintforest paintball servicios solicitados por este mismo para mejorar el Sitio Web y la experiencia del usuario al navegar en el Sitio Web. Los principales objetivos para los que se utilizan cookies de terceros son la obtenci\u00f3n de estad\u00edsticas de accesos y analizar la informaci\u00f3n de la navegaci\u00f3n, es decir, c\u00f3mo interact\u00faa el Usuario con el Sitio Web.<\/p><p>La informaci\u00f3n que se obtiene se refiere, por ejemplo, al n\u00famero de p\u00e1ginas visitadas, el idioma, el lugar a la que la direcci\u00f3n IP desde el que accede el Usuario, el n\u00famero de Usuarios que acceden, la frecuencia y reincidencia de las visitas, el tiempo de visita, el navegador que usan, el operador o tipo de dispositivo desde el que se realiza la visita. Esta informaci\u00f3n se utiliza para mejorar el Sitio Web, y detectar nuevas necesidades para ofrecer a los Usuarios un Contenido y\/o servicio de \u00f3ptima calidad. En todo caso, la informaci\u00f3n se recopila de forma an\u00f3nima y se elaboran informes de tendencias del Sitio Web sin identificar a usuarios individuales.<\/p><p>Puede obtener m\u00e1s informaci\u00f3n sobre las cookies, la informaci\u00f3n sobre la privacidad, o consultar la descripci\u00f3n del tipo de cookies que se utiliza, sus principales caracter\u00edsticas, periodo de expiraci\u00f3n, etc. en el siguiente(s) enlace(s):<\/p><p>La(s) entidad(es) encargada(s) del suministro de cookies podr\u00e1(n) ceder esta informaci\u00f3n a terceros, siempre y cuando lo exija la ley o sea un tercero el que procese esta informaci\u00f3n para dichas entidades.<\/p><h2>Cookies de redes sociales<\/h2><p>Paintforest paintball incorpora plugins de redes sociales, que permiten acceder a las mismas a partir del Sitio Web. Por esta raz\u00f3n, las cookies de redes sociales pueden almacenarse en el navegador del Usuario. Los titulares de dichas redes sociales disponen de sus propias pol\u00edticas de protecci\u00f3n de datos y de cookies, siendo ellos mismos, en cada caso, responsables de sus propios ficheros y de sus propias pr\u00e1cticas de privacidad. El Usuario debe referirse a las mismas para informarse acerca de dichas cookies y, en su caso, del tratamiento de sus datos personales. \u00danicamente a t\u00edtulo informativo se indican a continuaci\u00f3n los enlaces en los que se pueden consultar dichas pol\u00edticas de privacidad y\/o de cookies:<\/p><ul><li>Facebook: <a href=\"https:\/\/www.facebook.com\/policies\/cookies\/\">https:\/\/www.facebook.com\/policies\/cookies\/<\/a><\/li><li>Twitter: <a href=\"https:\/\/twitter.com\/es\/privacy\">https:\/\/twitter.com\/es\/privacy<\/a> <\/li><li>Instagram: <a href=\"https:\/\/help.instagram.com\/1896641480634370?ref=ig\">https:\/\/help.instagram.com\/1896641480634370?ref=ig<\/a> <\/li><li>YouTube: <a href=\"https:\/\/policies.google.com\/privacy?hl=es-419&amp;gl=mx\">https:\/\/policies.google.com\/privacy?hl=es-419&amp;gl=mx<\/a> <\/li><li>Pinterest: <a href=\"https:\/\/policy.pinterest.com\/es\/privacy-policy\">https:\/\/policy.pinterest.com\/es\/privacy-policy<\/a> <\/li><li>LinkedIn:<a href=\"https:\/\/www.linkedin.com\/legal\/cookie-policy?trk=hp-cookies\"> https:\/\/www.linkedin.com\/legal\/cookie-policy?trk=hp-cookies<\/a> <\/li><\/ul><h2>Deshabilitar, rechazar y eliminar cookies<\/h2><p>El Usuario puede deshabilitar, rechazar y eliminar las cookies \u2014total o parcialmente\u2014 instaladas en su dispositivo mediante la configuraci\u00f3n de su navegador (entre los que se encuentran, por ejemplo, Chrome, Firefox, Safari, Explorer). En este sentido, los procedimientos para rechazar y eliminar las cookies pueden diferir de un navegador de Internet a otro. En consecuencia, el Usuario debe acudir a las instrucciones facilitadas por el propio navegador de Internet que est\u00e9 utilizando. En el supuesto de que rechace el uso de cookies \u2014total o parcialmente\u2014 podr\u00e1 seguir usando el Sitio Web, si bien podr\u00e1 tener limitada la utilizaci\u00f3n de algunas de las prestaciones del mismo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de cookies El acceso a este Sitio Web puede implicar la utilizaci\u00f3n de cookies. Las cookies son peque\u00f1as cantidades de informaci\u00f3n que se almacenan en el navegador utilizado por cada Usuario \u2014en los distintos dispositivos que pueda utilizar para navegar\u2014 para que el servidor recuerde cierta informaci\u00f3n que posteriormente y \u00fanicamente el servidor que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-157","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de cookies - PaintForest<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de cookies - PaintForest\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de cookies El acceso a este Sitio Web puede implicar la utilizaci\u00f3n de cookies. Las cookies son peque\u00f1as cantidades de informaci\u00f3n que se almacenan en el navegador utilizado por cada Usuario \u2014en los distintos dispositivos que pueda utilizar para navegar\u2014 para que el servidor recuerde cierta informaci\u00f3n que posteriormente y \u00fanicamente el servidor que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paintforestpaintball.es\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"PaintForest\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T12:18:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.paintforestpaintball.es\\\/politica-de-cookies\\\/\",\"url\":\"https:\\\/\\\/www.paintforestpaintball.es\\\/politica-de-cookies\\\/\",\"name\":\"Pol\u00edtica de cookies - PaintForest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paintforestpaintball.es\\\/#website\"},\"datePublished\":\"2025-03-11T11:54:21+00:00\",\"dateModified\":\"2025-03-11T12:18:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.paintforestpaintball.es\\\/politica-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.paintforestpaintball.es\\\/politica-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.paintforestpaintball.es\\\/politica-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/paintforestpaintball.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paintforestpaintball.es\\\/#website\",\"url\":\"https:\\\/\\\/paintforestpaintball.es\\\/\",\"name\":\"PaintForest\",\"description\":\"Paintball Ja\u00e9n\",\"publisher\":{\"@id\":\"https:\\\/\\\/paintforestpaintball.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paintforestpaintball.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paintforestpaintball.es\\\/#organization\",\"name\":\"PaintForest\",\"url\":\"https:\\\/\\\/paintforestpaintball.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/paintforestpaintball.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/paintforestpaintball.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/RRSS_FACEBOOK_2reduc.webp\",\"contentUrl\":\"https:\\\/\\\/paintforestpaintball.es\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/RRSS_FACEBOOK_2reduc.webp\",\"width\":106,\"height\":70,\"caption\":\"PaintForest\"},\"image\":{\"@id\":\"https:\\\/\\\/paintforestpaintball.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de cookies - PaintForest","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Pol\u00edtica de cookies - PaintForest","og_description":"Pol\u00edtica de cookies El acceso a este Sitio Web puede implicar la utilizaci\u00f3n de cookies. Las cookies son peque\u00f1as cantidades de informaci\u00f3n que se almacenan en el navegador utilizado por cada Usuario \u2014en los distintos dispositivos que pueda utilizar para navegar\u2014 para que el servidor recuerde cierta informaci\u00f3n que posteriormente y \u00fanicamente el servidor que [&hellip;]","og_url":"https:\/\/www.paintforestpaintball.es\/politica-de-cookies\/","og_site_name":"PaintForest","article_modified_time":"2025-03-11T12:18:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paintforestpaintball.es\/politica-de-cookies\/","url":"https:\/\/www.paintforestpaintball.es\/politica-de-cookies\/","name":"Pol\u00edtica de cookies - PaintForest","isPartOf":{"@id":"https:\/\/paintforestpaintball.es\/#website"},"datePublished":"2025-03-11T11:54:21+00:00","dateModified":"2025-03-11T12:18:04+00:00","breadcrumb":{"@id":"https:\/\/www.paintforestpaintball.es\/politica-de-cookies\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paintforestpaintball.es\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.paintforestpaintball.es\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/paintforestpaintball.es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de cookies"}]},{"@type":"WebSite","@id":"https:\/\/paintforestpaintball.es\/#website","url":"https:\/\/paintforestpaintball.es\/","name":"PaintForest","description":"Paintball Ja\u00e9n","publisher":{"@id":"https:\/\/paintforestpaintball.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paintforestpaintball.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/paintforestpaintball.es\/#organization","name":"PaintForest","url":"https:\/\/paintforestpaintball.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/paintforestpaintball.es\/#\/schema\/logo\/image\/","url":"https:\/\/paintforestpaintball.es\/wp-content\/uploads\/2025\/03\/RRSS_FACEBOOK_2reduc.webp","contentUrl":"https:\/\/paintforestpaintball.es\/wp-content\/uploads\/2025\/03\/RRSS_FACEBOOK_2reduc.webp","width":106,"height":70,"caption":"PaintForest"},"image":{"@id":"https:\/\/paintforestpaintball.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/paintforestpaintball.es\/en\/wp-json\/wp\/v2\/pages\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paintforestpaintball.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paintforestpaintball.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paintforestpaintball.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paintforestpaintball.es\/en\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":10,"href":"https:\/\/paintforestpaintball.es\/en\/wp-json\/wp\/v2\/pages\/157\/revisions"}],"predecessor-version":[{"id":208,"href":"https:\/\/paintforestpaintball.es\/en\/wp-json\/wp\/v2\/pages\/157\/revisions\/208"}],"wp:attachment":[{"href":"https:\/\/paintforestpaintball.es\/en\/wp-json\/wp\/v2\/media?parent=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}